{"id":2283,"date":"2019-09-18T13:11:47","date_gmt":"2019-09-18T17:11:47","guid":{"rendered":"https:\/\/sonora.ms.gov.br\/v2\/?p=2283"},"modified":"2024-10-07T10:43:29","modified_gmt":"2024-10-07T14:43:29","slug":"eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro","status":"publish","type":"post","link":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/","title":{"rendered":"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro"},"content":{"rendered":"<p style=\"background: white; margin: 0cm 0cm 19.5pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Verdana',sans-serif; color: #222222;\">O Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA), divulga a rela\u00e7\u00e3o dos candidatos aptos a serem votados no Processo de Escolha dos Conselheiros Tutelares, ano de 2019. <span style=\"background: white;\">Ser\u00e3o 5 (cinco) vagas para membros titulares e demais suplentes, com candidaturas individuais<\/span>.<\/span><\/p>\n<p style=\"background: white; margin: 0cm 0cm 19.5pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Verdana',sans-serif; color: #222222;\">A elei\u00e7\u00e3o acontecer\u00e1 dia no dia 06 de outubro, <span style=\"background: white;\">atrav\u00e9s de voto facultativo e secreto <\/span>das 08 \u00e0s 17 horas na escola Municipal Francesco Batista Giobbi<span style=\"background: white;\">, e poder\u00e3o votar todos os cidad\u00e3os de Sonora acima de 16 anos e que estejam quites com a Justi\u00e7a Eleitoral. O Minist\u00e9rio P\u00fablico, se encarregar\u00e1 da fiscaliza\u00e7\u00e3o de todo o processo de escolha dos membros do Conselho Tutelar de Sonora.<\/span> <\/span>Os eleitores devem levar no dia o T\u00edtulo de Eleitor e um documento com foto.<\/p>\n<p style=\"background: white; margin: 0cm 0cm 19.5pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Verdana',sans-serif; color: #222222; background: white;\">A forma\u00e7\u00e3o e certifica\u00e7\u00e3o dos conselheiros tutelares titulares e suplentes, ser\u00e1 de responsabilidade da Ger\u00eancia Municipal de Assist\u00eancia Social e Trabalho, coordenado pelo CMDCA. Os conselheiros Tutelares titulares ser\u00e3o empossados pelo prefeito municipal no dia 10 de janeiro de 2020.<\/span><\/p>\n<p style=\"background: white; box-sizing: border-box; overflow-wrap: break-word; font-variant-ligatures: normal; font-variant-caps: normal; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px; margin: 0cm 0cm 19.5pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Verdana',sans-serif; color: #222222;\">Para maiores informa\u00e7\u00f5es os interessados devem procurar o Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente, sito a Rua Adalberto Bozoki, 276 \u2013 telefone (67) 3254-1821.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA), divulga a rela\u00e7\u00e3o dos candidatos aptos a serem votados no Processo de Escolha dos Conselheiros Tutelares, ano de 2019. Ser\u00e3o 5 (cinco) vagas para membros titulares e demais suplentes, com candidaturas individuais. A elei\u00e7\u00e3o acontecer\u00e1 dia no dia 06 de outubro, atrav\u00e9s de voto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,3],"tags":[],"class_list":["post-2283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assistencia-social-e-trabalho","category-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro - Prefeitura Municipal de Sonora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro - Prefeitura Municipal de Sonora\" \/>\n<meta property=\"og:description\" content=\"O Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA), divulga a rela\u00e7\u00e3o dos candidatos aptos a serem votados no Processo de Escolha dos Conselheiros Tutelares, ano de 2019. Ser\u00e3o 5 (cinco) vagas para membros titulares e demais suplentes, com candidaturas individuais. A elei\u00e7\u00e3o acontecer\u00e1 dia no dia 06 de outubro, atrav\u00e9s de voto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura Municipal de Sonora\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Prefeitura-Municipal-de-Sonora-320210145060198\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T17:11:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T14:43:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sonora.ms.gov.br\/v2\/wp-content\/uploads\/2019\/09\/cartaz-candidatos-conselho-tutelar-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4726\" \/>\n\t<meta property=\"og:image:height\" content=\"3544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adeildo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adeildo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/\"},\"author\":{\"name\":\"adeildo\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/#\\\/schema\\\/person\\\/51f6e139289b09c05a59bc20aaab8a50\"},\"headline\":\"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro\",\"datePublished\":\"2019-09-18T17:11:47+00:00\",\"dateModified\":\"2024-10-07T14:43:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/\"},\"wordCount\":208,\"image\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/cartaz-candidatos-conselho-tutelar-1.jpg\",\"articleSection\":[\"Assist\u00eancia Social e Trabalho\",\"Destaque\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/\",\"url\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/\",\"name\":\"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro - Prefeitura Municipal de Sonora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/cartaz-candidatos-conselho-tutelar-1.jpg\",\"datePublished\":\"2019-09-18T17:11:47+00:00\",\"dateModified\":\"2024-10-07T14:43:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/#\\\/schema\\\/person\\\/51f6e139289b09c05a59bc20aaab8a50\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/cartaz-candidatos-conselho-tutelar-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/cartaz-candidatos-conselho-tutelar-1.jpg\",\"width\":4726,\"height\":3544},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/#website\",\"url\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/\",\"name\":\"Prefeitura Municipal de Sonora\",\"description\":\"Poder Executivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/#\\\/schema\\\/person\\\/51f6e139289b09c05a59bc20aaab8a50\",\"name\":\"adeildo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5765d730d44ab1af4a323cac96b3222e77c35c973674361c1bc200f3915939f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5765d730d44ab1af4a323cac96b3222e77c35c973674361c1bc200f3915939f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5765d730d44ab1af4a323cac96b3222e77c35c973674361c1bc200f3915939f?s=96&d=mm&r=g\",\"caption\":\"adeildo\"},\"url\":\"https:\\\/\\\/sonora.ms.gov.br\\\/v2\\\/author\\\/adeildo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro - Prefeitura Municipal de Sonora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/","og_locale":"pt_BR","og_type":"article","og_title":"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro - Prefeitura Municipal de Sonora","og_description":"O Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA), divulga a rela\u00e7\u00e3o dos candidatos aptos a serem votados no Processo de Escolha dos Conselheiros Tutelares, ano de 2019. Ser\u00e3o 5 (cinco) vagas para membros titulares e demais suplentes, com candidaturas individuais. A elei\u00e7\u00e3o acontecer\u00e1 dia no dia 06 de outubro, atrav\u00e9s de voto [&hellip;]","og_url":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/","og_site_name":"Prefeitura Municipal de Sonora","article_publisher":"https:\/\/www.facebook.com\/Prefeitura-Municipal-de-Sonora-320210145060198","article_published_time":"2019-09-18T17:11:47+00:00","article_modified_time":"2024-10-07T14:43:29+00:00","og_image":[{"width":4726,"height":3544,"url":"https:\/\/sonora.ms.gov.br\/v2\/wp-content\/uploads\/2019\/09\/cartaz-candidatos-conselho-tutelar-1.jpg","type":"image\/jpeg"}],"author":"adeildo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adeildo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#article","isPartOf":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/"},"author":{"name":"adeildo","@id":"https:\/\/sonora.ms.gov.br\/v2\/#\/schema\/person\/51f6e139289b09c05a59bc20aaab8a50"},"headline":"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro","datePublished":"2019-09-18T17:11:47+00:00","dateModified":"2024-10-07T14:43:29+00:00","mainEntityOfPage":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/"},"wordCount":208,"image":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#primaryimage"},"thumbnailUrl":"https:\/\/sonora.ms.gov.br\/v2\/wp-content\/uploads\/2019\/09\/cartaz-candidatos-conselho-tutelar-1.jpg","articleSection":["Assist\u00eancia Social e Trabalho","Destaque"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/","url":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/","name":"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro - Prefeitura Municipal de Sonora","isPartOf":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#primaryimage"},"image":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#primaryimage"},"thumbnailUrl":"https:\/\/sonora.ms.gov.br\/v2\/wp-content\/uploads\/2019\/09\/cartaz-candidatos-conselho-tutelar-1.jpg","datePublished":"2019-09-18T17:11:47+00:00","dateModified":"2024-10-07T14:43:29+00:00","author":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/#\/schema\/person\/51f6e139289b09c05a59bc20aaab8a50"},"breadcrumb":{"@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#primaryimage","url":"https:\/\/sonora.ms.gov.br\/v2\/wp-content\/uploads\/2019\/09\/cartaz-candidatos-conselho-tutelar-1.jpg","contentUrl":"https:\/\/sonora.ms.gov.br\/v2\/wp-content\/uploads\/2019\/09\/cartaz-candidatos-conselho-tutelar-1.jpg","width":4726,"height":3544},{"@type":"BreadcrumbList","@id":"https:\/\/sonora.ms.gov.br\/v2\/eleicao-para-conselheiras-tutelares-acontece-dia-06-de-outubro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sonora.ms.gov.br\/v2\/"},{"@type":"ListItem","position":2,"name":"Elei\u00e7\u00e3o para conselheiras tutelares acontece dia 06 de outubro"}]},{"@type":"WebSite","@id":"https:\/\/sonora.ms.gov.br\/v2\/#website","url":"https:\/\/sonora.ms.gov.br\/v2\/","name":"Prefeitura Municipal de Sonora","description":"Poder Executivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sonora.ms.gov.br\/v2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/sonora.ms.gov.br\/v2\/#\/schema\/person\/51f6e139289b09c05a59bc20aaab8a50","name":"adeildo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5765d730d44ab1af4a323cac96b3222e77c35c973674361c1bc200f3915939f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5765d730d44ab1af4a323cac96b3222e77c35c973674361c1bc200f3915939f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5765d730d44ab1af4a323cac96b3222e77c35c973674361c1bc200f3915939f?s=96&d=mm&r=g","caption":"adeildo"},"url":"https:\/\/sonora.ms.gov.br\/v2\/author\/adeildo\/"}]}},"_links":{"self":[{"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/posts\/2283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/comments?post=2283"}],"version-history":[{"count":3,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/posts\/2283\/revisions"}],"predecessor-version":[{"id":3792,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/posts\/2283\/revisions\/3792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/media\/2287"}],"wp:attachment":[{"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/media?parent=2283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/categories?post=2283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonora.ms.gov.br\/v2\/wp-json\/wp\/v2\/tags?post=2283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}